{"id":5927,"date":"2013-05-13T23:21:01","date_gmt":"2013-05-13T21:21:01","guid":{"rendered":"http:\/\/www.imakeyousmile.se\/?p=5927"},"modified":"2013-05-13T23:21:01","modified_gmt":"2013-05-13T21:21:01","slug":"summer-ny-palett","status":"publish","type":"post","link":"https:\/\/www.imakeyousmile.se\/es\/paleta-nueva-de-verano\/","title":{"rendered":"Verano - \u00a1Nueva paleta!"},"content":{"rendered":"<p>Frida me pregunt\u00f3 si ten\u00eda tiempo para hablar por tel\u00e9fono.<\/p>\n<p><em>&quot;Absolutamente, pero no por mucho tiempo<\/em>&quot; Respond\u00ed.<\/p>\n<p>Despu\u00e9s de hablar un rato, mir\u00e9 el reloj. Hab\u00edamos hablado en <strong>dos horas<\/strong>\u00a1\u00a1Y ya eran las siete y media de la tarde !!<\/p>\n<p>Qu\u00e9 pas\u00f3 como, jaja. De ah\u00ed el post tard\u00edo de hoy, tambi\u00e9n hay que tomar el autob\u00fas 6 para trabajar ma\u00f1ana y trabajar hasta al menos las 20.00. La vida es dura\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>De todos modos, \u00a1aqu\u00ed viene el maquillaje de hoy!<\/p>\n<p>Se publicar\u00e1 paso a paso tan pronto como tenga tiempo, y tambi\u00e9n se hace una sola <strong>nueva paleta<\/strong> que estar\u00e1 en la tienda pronto! :)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.imakeyousmile.se\/es\/summer-ny-palett\/img_0961\/\" rel=\"attachment wp-att-5931\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-5931\" title=\"IMG_0961\" src=\"http:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_0961-1024x776.jpg\" alt=\"\" width=\"706\" height=\"534\" srcset=\"https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_0961-1024x776.jpg 1024w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_0961-300x227.jpg 300w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_0961-940x712.jpg 940w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_0961-620x469.jpg 620w\" sizes=\"(max-width: 706px) 100vw, 706px\" \/><\/a><br \/>\n<a href=\"http:\/\/www.imakeyousmile.se\/es\/summer-ny-palett\/img_1109-kopia\/\" rel=\"attachment wp-att-5928\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-5928\" title=\"IMG_1109 - copiar\" src=\"http:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-kopia-1024x630.jpg\" alt=\"\" width=\"784\" height=\"482\" srcset=\"https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-kopia-1024x630.jpg 1024w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-kopia-300x184.jpg 300w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-kopia-940x578.jpg 940w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-kopia-620x381.jpg 620w\" sizes=\"(max-width: 784px) 100vw, 784px\" \/><\/a><a href=\"http:\/\/www.imakeyousmile.se\/es\/summer-ny-palett\/img_1109\/\" rel=\"attachment wp-att-5929\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-5929\" title=\"IMG_1109\" src=\"http:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-961x1024.jpg\" alt=\"\" width=\"673\" height=\"717\" srcset=\"https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-961x1024.jpg 961w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-281x300.jpg 281w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-940x1001.jpg 940w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109-620x660.jpg 620w, https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1109.jpg 1752w\" sizes=\"(max-width: 673px) 100vw, 673px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"IMG_1131\" src=\"http:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_1131-763x1024.jpg\" alt=\"\" width=\"763\" height=\"1024\" \/><\/p>\n<p>\u00a1Ahora tengo que dormir, para poder dormir al menos 5 horas! :)<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Frida fr\u00e5gade om jag hade tid att prata i telefon. &#8221;Absolut, men inte superl\u00e4nge&#8221; svarade jag. Efter att ha pratat en stund, s\u00e5 tittade jag p\u00e5 klockan. Vi hade\u00a0pratat i tv\u00e5 timmar, och klockan var redan halv 8 p\u00e5 kv\u00e4llen!! Vad h\u00e4nde liksom, haha. D\u00e4rav sent inl\u00e4gg idag, m\u00e5ste dessutom ta 6-bussen till jobbet imorgon [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[715,48,409],"class_list":["post-5927","post","type-post","status-publish","format-standard","hentry","category-allmant","tag-40-palett","tag-fargglad-sminkning","tag-sommarsminkning"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v14.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"Summer - Ny palett! | Helena Amiley - H\u00e4r hittar du senaste infromation om sk\u00f6nhet, livsstil, entrepren\u00f6rskap, makeup &amp; tips.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imakeyousmile.se\/es\/summer-ny-palett\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Summer - Ny palett! | Imakeyousmile.se\" \/>\n<meta property=\"og:description\" content=\"Summer - Ny palett! | Helena Amiley - H\u00e4r hittar du senaste infromation om sk\u00f6nhet, livsstil, entrepren\u00f6rskap, makeup &amp; tips.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imakeyousmile.se\/es\/summer-ny-palett\/\" \/>\n<meta property=\"og:site_name\" content=\"Imakeyousmile.se\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/imakeyousmile.se\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-13T21:21:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_0961-1024x776.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#organization\",\"name\":\"Imakeyousmile\",\"url\":\"https:\/\/www.imakeyousmile.se\/es\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2020\/10\/HELENA-AMILEY_SVART-1-e1603367975324.png\",\"width\":280,\"height\":93,\"caption\":\"Imakeyousmile\"},\"image\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#website\",\"url\":\"https:\/\/www.imakeyousmile.se\/es\/\",\"name\":\"Imakeyousmile.se\",\"description\":\"Helena Amiley - Beauty, Entrepreneur, Lifestyle\",\"publisher\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.imakeyousmile.se\/es\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/www.imakeyousmile.se\/wp-content\/uploads\/2013\/05\/IMG_0961-1024x776.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/#webpage\",\"url\":\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/\",\"name\":\"Summer - Ny palett! | Imakeyousmile.se\",\"isPartOf\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/#primaryimage\"},\"datePublished\":\"2013-05-13T21:21:01+00:00\",\"dateModified\":\"2013-05-13T21:21:01+00:00\",\"description\":\"Summer - Ny palett! | Helena Amiley - H\\u00e4r hittar du senaste infromation om sk\\u00f6nhet, livsstil, entrepren\\u00f6rskap, makeup & tips.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#\/schema\/person\/b0fd43b1c6bb1c60cfd68bff9b4a10fb\"},\"headline\":\"Summer &#8211; Ny palett!\",\"datePublished\":\"2013-05-13T21:21:01+00:00\",\"dateModified\":\"2013-05-13T21:21:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/#primaryimage\"},\"keywords\":\"40 palett,F\\u00e4rgglad sminkning,Sommarsminkning\",\"articleSection\":\"\\u00d6vrigt\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.imakeyousmile.se\/summer-ny-palett\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#\/schema\/person\/b0fd43b1c6bb1c60cfd68bff9b4a10fb\",\"name\":\"Helena Amiley\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.imakeyousmile.se\/es\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5645558e1e355457a23368d7e1b4c904?s=96&d=mm&r=g\",\"caption\":\"Helena Amiley\"},\"description\":\"Jag skriver mest om sk\\u00f6nhet men bjuder \\u00e4ven p\\u00e5 glimtar fr\\u00e5n entrepren\\u00f6rlivet och bygget av v\\u00e5r egen camper van. Vanlife here we come!\",\"sameAs\":[\"https:\/\/www.facebook.com\/imakeyousmile.se\",\"https:\/\/www.instagram.com\/helenaamiley\",\"https:\/\/www.youtube.com\/channel\/UCR5iB6rvpV6Yr8ZjpQfr5mg?view_as=subscriber\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/posts\/5927"}],"collection":[{"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/comments?post=5927"}],"version-history":[{"count":0,"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/posts\/5927\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/media?parent=5927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/categories?post=5927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.imakeyousmile.se\/es\/wp-json\/wp\/v2\/tags?post=5927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}